{"id":872,"date":"2023-12-04T23:56:15","date_gmt":"2023-12-04T23:56:15","guid":{"rendered":"https:\/\/somososom.com\/product\/chalo-cardamomo\/"},"modified":"2025-11-04T14:43:27","modified_gmt":"2025-11-04T14:43:27","slug":"chalo-cardamomo","status":"publish","type":"product","link":"https:\/\/somososom.com\/es\/product\/chalo-cardamomo\/","title":{"rendered":"Chalo Cardamomo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1557,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":{"0":"post-872","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tes-infusiones","7":"member-discount","8":"discount-restricted","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product\/872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/comments?post=872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/media\/1557"}],"wp:attachment":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/media?parent=872"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product_brand?post=872"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product_cat?post=872"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product_tag?post=872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}