{"id":1421,"date":"2024-03-21T10:39:41","date_gmt":"2024-03-21T10:39:41","guid":{"rendered":"https:\/\/somososom.com\/?post_type=product&#038;p=1421"},"modified":"2025-08-11T10:39:18","modified_gmt":"2025-08-11T10:39:18","slug":"osom-coffee-chaos-cap","status":"publish","type":"product","link":"https:\/\/somososom.com\/es\/product\/osom-coffee-chaos-cap\/","title":{"rendered":"BLOSSOM OSOM COFFEE &#038; CHAOS CAP"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>COFFEE & CHAOS CAP<\/strong><\/p>\n<p style=\"text-align: center;\">Gorra bordada a mano ajustable para un fit perfecto<\/p>\n<p style=\"text-align: center;\">Coffee & Chaos por delante, Osom por detr\u00e1s.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><strong>COFFEE &amp; CHAOS CAP<\/strong><\/p>\n<p style=\"text-align: center;\">Gorra bordada y ajustable para fit perfecto<\/p>\n<p style=\"text-align: center;\">Coffee &amp; Chaos por delante, Osom por detr\u00e1s<\/p>\n","protected":false},"featured_media":1424,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[85,30],"product_tag":[],"class_list":{"0":"post-1421","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-blossom-collection","7":"product_cat-osom","8":"member-discount","9":"discount-restricted","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product\/1421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/comments?post=1421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/media\/1424"}],"wp:attachment":[{"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/media?parent=1421"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product_brand?post=1421"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product_cat?post=1421"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/somososom.com\/es\/wp-json\/wp\/v2\/product_tag?post=1421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}